{"id":42932,"date":"2026-07-15T15:04:11","date_gmt":"2026-07-15T13:04:11","guid":{"rendered":"https:\/\/sereniorizzonti.it\/?p=42932"},"modified":"2026-07-15T15:04:13","modified_gmt":"2026-07-15T13:04:13","slug":"la-rsa-e-poliambulatorio-villa-chiara-a-roma-entra-nel-gruppo-sereni-orizzonti","status":"publish","type":"post","link":"https:\/\/sereniorizzonti.it\/it\/la-rsa-e-poliambulatorio-villa-chiara-a-roma-entra-nel-gruppo-sereni-orizzonti\/","title":{"rendered":"La RSA e poliambulatorio Villa Chiara a Roma entra nel Gruppo Sereni Orizzonti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Cambia propriet\u00e0 Villa Chiara, storica RSA della Capitale da 70 posti letto: la struttura entra ora nel gruppo Sereni Orizzonti 1 S.p.A., tra i principali operatori italiani nella costruzione e gestione di residenze sanitarie assistenziali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per l&#8217;articolo completo \ud83d\udc47<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.newtuscia.it\/2026\/07\/15\/la-rsa-e-poliambulatorio-villa-chiara-a-roma-entra-nel-gruppo-sereni-orizzonti\">https:\/\/www.newtuscia.it\/2026\/07\/15\/la-rsa-e-poliambulatorio-villa-chiara-a-roma-entra-nel-gruppo-sereni-orizzonti<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.controluce.it\/cambio-di-proprieta-per-villa-chiara\/\">https:\/\/www.controluce.it\/cambio-di-proprieta-per-villa-chiara\/<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Cambia propriet\u00e0 Villa Chiara, storica RSA della Capitale da 70 posti letto: la struttura entra ora nel gruppo Sereni Orizzonti 1 S.p.A., tra i principali operatori italiani nella costruzione e gestione di residenze sanitarie assistenziali. Per l&#8217;articolo completo \ud83d\udc47<\/p>\n","protected":false},"author":1,"featured_media":42933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[48],"tags":[],"class_list":["post-42932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-corporate"],"acf":[],"_links":{"self":[{"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/posts\/42932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/comments?post=42932"}],"version-history":[{"count":1,"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/posts\/42932\/revisions"}],"predecessor-version":[{"id":42934,"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/posts\/42932\/revisions\/42934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/media\/42933"}],"wp:attachment":[{"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/media?parent=42932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/categories?post=42932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/tags?post=42932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}