{"id":40740,"date":"2019-09-06T00:00:00","date_gmt":"2019-09-05T22:00:00","guid":{"rendered":"https:\/\/sereniorizzonti.it\/?p=40740"},"modified":"2024-09-26T15:58:21","modified_gmt":"2024-09-26T13:58:21","slug":"sereni-orizzonti-200-milioni-di-fatturato-i-nostri-numeri","status":"publish","type":"post","link":"https:\/\/sereniorizzonti.it\/it\/sereni-orizzonti-200-milioni-di-fatturato-i-nostri-numeri\/","title":{"rendered":"Sereni Orizzonti 200 milioni di fatturato: i nostri numeri"},"content":{"rendered":"<p><span style=\"font-family: \" lucida=\"\" grande\",=\"\" sans-serif;=\"\" font-size:=\"\" 11px;\"=\"\">06.09.2019 &#8211; RSA: Sereni Orizzonti leader nazionale nel settore socio-sanitario\u00a0<\/span><span style=\"font-family: \" lucida=\"\" grande\",=\"\" sans-serif;=\"\" font-size:=\"\" 11px;\"=\"\"><br \/><\/span><span style=\"font-family: \" lucida=\"\" grande\",=\"\" sans-serif;=\"\" font-size:=\"\" 11px;\"=\"\"><br \/><\/span><span style=\"\" lucida=\"\" grande\",=\"\" sans-serif;=\"\" font-size:=\"\" 11px;\"=\"\">5600 POSTI LETTOSono ormai 5.600 i posti letto che Sereni Orizzontimette a disposizione delle comunit\u00e0 e stimiamodi sfiorare quota 10.000 entro il 2021: numeriche pongono l\u2019Azienda fra i principali protagonistidel settore socio-sanitario italiano.<br \/>3.000 DIPENDENTIIl personale \u00e8 formato da professionisti competentie specializzati in grado di seguire con attenzionee umanit\u00e0 le delicate situazioni degli ospiti anziani,autosufficienti e non. Sereni Orizzonti 1 S.p.A.stima di raggiungere i 3.600 occupati entro il 2020e il numero dei dipendenti cresce continuamente.Siamo orgogliosi del fatto che si tratti, in largamaggioranza, di occupazione femminile.<br \/><span style=\"font-size: 11px;\">90 STRUTTURE<\/span><span style=\"font-size: 11px;\">Partendo da Udine e dal Friuli Venezia Giulia,<\/span><span style=\"font-size: 11px;\">il Gruppo si \u00e8 esteso negli ultimi vent\u2019anni<\/span><span style=\"font-size: 11px;\">fino a essere presente con 90 strutture<\/span><span style=\"font-size: 11px;\">in tutta Italia. Cresciamo costruendo<\/span><span style=\"font-size: 11px;\">10 nuove residenze all\u2019anno.<\/span><span style=\"font-size: 11px;\"><br \/><\/span><span style=\"font-size: 11px;\">FATTURATO E INVESTIMENTI\u00a0<\/span><span style=\"font-size: 11px;\">Il fatturato di gruppo consolidato in via di conseguimento per il 2019 supera i 200 milioni di euro ben 40 in pi\u00f9 (il 25 per cento) rispetto all&#8217;anno passato quando si era attestato a 160 milioni, 77 in pi\u00f9 rispetto al 2017. Quanto agli utili netti nel 2018 hanno superato i 13 milioni di euro. Un contributo decisivo al conseguimento di questi risultati \u00e8 avvenuto dagli importanti\u00a0investimenti realizzati che per il triennio 2019-2021 prevede di &#8220;spendere&#8221; ben 320 milioni. Duecento per la realizzazione di nuove RSA in Italia e il resto per altri interventi estero compreso.\u00a0<\/span><span style=\"font-size: 11px;\"><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>06.09.2019 &#8211; RSA: Sereni Orizzonti leader nazionale nel settore socio-sanitario\u00a05600 POSTI LETTOSono ormai 5.600 i posti letto che Sereni Orizzontimette a disposizione delle comunit\u00e0 e stimiamodi sfiorare quota 10.000 entro il 2021: numeriche pongono l\u2019Azienda fra i principali protagonistidel settore socio-sanitario italiano.3.000 DIPENDENTIIl personale \u00e8 formato da professionisti competentie specializzati in grado di seguire con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[48],"tags":[],"class_list":["post-40740","post","type-post","status-publish","format-standard","hentry","category-news-corporate"],"acf":[],"_links":{"self":[{"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/posts\/40740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/comments?post=40740"}],"version-history":[{"count":1,"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/posts\/40740\/revisions"}],"predecessor-version":[{"id":40998,"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/posts\/40740\/revisions\/40998"}],"wp:attachment":[{"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/media?parent=40740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/categories?post=40740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sereniorizzonti.it\/it\/wp-json\/wp\/v2\/tags?post=40740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}