{"id":41779,"date":"2025-06-05T15:34:47","date_gmt":"2025-06-05T13:34:47","guid":{"rendered":"https:\/\/sereniorizzonti.it\/?post_type=residenza&#038;p=41779"},"modified":"2026-05-04T14:49:46","modified_gmt":"2026-05-04T12:49:46","slug":"residenza-caris","status":"publish","type":"residenza","link":"https:\/\/sereniorizzonti.it\/es\/residenza\/residenza-caris\/","title":{"rendered":"RESIDENCIA 'Caris"},"content":{"rendered":"<p>La Residenza Protetta \u201cCaris\u201d \u00e8 una struttura a valenza socio-sanitaria che dispone complessivamente di 60 posti letto ed \u00e8 rivolta all\u2019accoglienza di persone anziane e non anziane non autosufficienti. La struttura \u00e8 organizzata per garantire un\u2019assistenza continua e qualificata, rispondendo ai diversi bisogni degli ospiti.<\/p>\n\n\n\n<p>La residenza \u00e8 caratterizzata da ambienti colorati e specificamente arredati, con percorsi interni progettati in modo protesico e funzionale. Gli ospiti possono inoltre usufruire di un ampio giardino esterno, pensato per favorire il benessere e la socializzazione.<\/p>\n\n\n\n<p>Le camere, singole o doppie, sono tutte dotate di servizi igienici interni, aria climatizzata, telefono, televisione e letti ortopedici ad altezza variabile, garantendo comfort, sicurezza e adeguata assistenza.<\/p>\n\n\n\n<p>Al piano seminterrato si trovano la sala da pranzo, la palestra per la fisioterapia di gruppo e individuale e la sala polivalente destinata alle attivit\u00e0 ricreative e occupazionali, tutti spazi con accesso diretto al cortile esterno. Nello stesso piano sono presenti anche l\u2019infermeria e i locali destinati alla lavanderia.<\/p>\n\n\n\n<p>Al piano rialzato e al piano primo sono collocate le stanze di degenza, gli ambulatori di reparto, i bagni assistiti e i soggiorni di piano. La reception si trova all\u2019ingresso, al piano rialzato, mentre gli uffici amministrativi e la direzione sono situati al piano primo.<\/p>\n\n\n\n<p>Ogni piano \u00e8 servito da ascensore e montalettighe, che garantiscono la piena accessibilit\u00e0 e la gestione agevole degli spostamenti degli ospiti.<\/p>\n\n\n\n<p>La struttura \u00e8 accessibile in automobile attraverso le principali arterie stradali della zona, che consentono di arrivare agevolmente nei pressi dell\u2019edificio; sono inoltre presenti aree di sosta dedicate che facilitano l\u2019arrivo di familiari e visitatori.<\/p>","protected":false},"featured_media":41780,"template":"","meta":{"_acf_changed":false},"area-goegrafica-residenza":[107],"provincia-residenza":[101],"regione-residenza":[65],"servizi-della-residenza":[147,108,109,110,112,113,155,116,117,144,142],"societa-rsa":[135],"stato-struttura":[57],"il-nostro-servizio":[61],"class_list":["post-41779","residenza","type-residenza","status-publish","has-post-thumbnail","hentry","area-goegrafica-residenza-italia","provincia-residenza-udine-friuli-venezia-giulia","regione-residenza-friuli-venezia-giulia","servizi-della-residenza-arteterapia","servizi-della-residenza-assistenza-infermieristica","servizi-della-residenza-assistenza-medica","servizi-della-residenza-assistenza-religiosa","servizi-della-residenza-estetista","servizi-della-residenza-fisioterapia","servizi-della-residenza-ingresso-immediato-in-base-alla-lista-dattesa-e-alla-disponibilita-di-posti-letto","servizi-della-residenza-parrucchiere","servizi-della-residenza-percorsi-fisioterapici-personalizzati","servizi-della-residenza-progetti-educativi-individualizzati","servizi-della-residenza-supporto-psicologico","societa-rsa-sereni-orizzonti-1","stato-struttura-attiva","il-nostro-servizio-residenze-sanitarie-per-anziani"],"acf":[],"_links":{"self":[{"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/residenza\/41779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/residenza"}],"about":[{"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/types\/residenza"}],"version-history":[{"count":3,"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/residenza\/41779\/revisions"}],"predecessor-version":[{"id":42526,"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/residenza\/41779\/revisions\/42526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/media\/41780"}],"wp:attachment":[{"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/media?parent=41779"}],"wp:term":[{"taxonomy":"area-goegrafica-residenza","embeddable":true,"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/area-goegrafica-residenza?post=41779"},{"taxonomy":"provincia-residenza","embeddable":true,"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/provincia-residenza?post=41779"},{"taxonomy":"regione-residenza","embeddable":true,"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/regione-residenza?post=41779"},{"taxonomy":"servizi-della-residenza","embeddable":true,"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/servizi-della-residenza?post=41779"},{"taxonomy":"societa-rsa","embeddable":true,"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/societa-rsa?post=41779"},{"taxonomy":"stato-struttura","embeddable":true,"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/stato-struttura?post=41779"},{"taxonomy":"il-nostro-servizio","embeddable":true,"href":"https:\/\/sereniorizzonti.it\/es\/wp-json\/wp\/v2\/il-nostro-servizio?post=41779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}